{"id":18749,"date":"2025-11-03T10:57:04","date_gmt":"2025-11-03T07:27:04","guid":{"rendered":"https:\/\/kebrin.ir\/mag\/?p=18749"},"modified":"2025-11-03T10:57:04","modified_gmt":"2025-11-03T07:27:04","slug":"crypto-whales-btc-eth-aster-sol-hype-ghost","status":"publish","type":"post","link":"https:\/\/kebrin.ir\/mag\/crypto-whales-btc-eth-aster-sol-hype-ghost","title":{"rendered":"\u0646\u0647\u0646\u06af\u200c\u0647\u0627\u06cc \u06a9\u0631\u06cc\u067e\u062a\u0648 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0627\u0641\u062a \u0628\u0627\u0632\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u06a9\u062c\u0627 \u0645\u06cc\u200c\u0628\u0631\u0646\u062f\u061f"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 ez-toc-wrap-left-text counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/kebrin.ir\/mag\/crypto-whales-btc-eth-aster-sol-hype-ghost\/#%D9%86%D9%87%D9%86%DA%AF%E2%80%8C%D9%87%D8%A7_%D8%A8%D8%A7_%D8%AA%D8%B1%D8%A7%DA%A9%D9%86%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A8%D8%B2%D8%B1%DA%AF_%D9%BE%D8%B1%D8%AA%D9%81%D9%88%DB%8C_%D8%AE%D9%88%D8%AF_%D8%B1%D8%A7_%D8%A8%D8%A7%D8%B2%D8%AA%D9%88%D8%B2%DB%8C%D8%B9_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D9%86%D8%AF\" >\u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u0628\u0627 \u062a\u0631\u0627\u06a9\u0646\u0634\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u067e\u0631\u062a\u0641\u0648\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0632\u062a\u0648\u0632\u06cc\u0639 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/kebrin.ir\/mag\/crypto-whales-btc-eth-aster-sol-hype-ghost\/#%D8%AA%D9%88%D8%AC%D9%87_%D9%86%D9%87%D9%86%DA%AF%E2%80%8C%D9%87%D8%A7_%D8%A8%D9%87_%D8%A2%D9%84%D8%AA%E2%80%8C%DA%A9%D9%88%DB%8C%D9%86%E2%80%8C%D9%87%D8%A7\" >\u062a\u0648\u062c\u0647 \u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u0628\u0647 \u0622\u0644\u062a\u200c\u06a9\u0648\u06cc\u0646\u200c\u0647\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/kebrin.ir\/mag\/crypto-whales-btc-eth-aster-sol-hype-ghost\/#%D9%85%D9%88%D9%82%D8%B9%DB%8C%D8%AA_%D9%86%D9%87%D9%86%DA%AF%E2%80%8C%D9%87%D8%A7_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%D9%85%D8%B4%D8%AA%D9%82%D8%A7%D8%AA\" >\u0645\u0648\u0642\u0639\u06cc\u062a \u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0634\u062a\u0642\u0627\u062a<\/a><\/li><\/ul><\/nav><\/div>\n<p><span style=\"font-weight: 400;\">\u0628\u0627\u0632\u0627\u0631 \u0631\u0645\u0632\u0627\u0631\u0632\u0647\u0627 \u062f\u0631 \u0633\u0627\u0639\u0627\u062a \u0627\u0628\u062a\u062f\u0627\u06cc\u06cc \u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0622\u0633\u06cc\u0627\u06cc\u06cc \u0631\u0648\u0632 \u062f\u0648\u0634\u0646\u0628\u0647\u060c \u0633\u0648\u062f \u0622\u062e\u0631 \u0647\u0641\u062a\u0647 \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f \u0648 \u0628\u0627 \u0648\u062c\u0648\u062f \u06a9\u0627\u0647\u0634 \u062a\u0646\u0634\u200c\u0647\u0627\u06cc \u062a\u062c\u0627\u0631\u06cc \u062c\u0647\u0627\u0646\u06cc\u060c \u0628\u0647 \u06f3.\u06f5\u06f9 \u062a\u0631\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0633\u0642\u0648\u0637 \u06a9\u0631\u062f. \u062f\u0631 \u0647\u0645\u06cc\u0646 \u062d\u0627\u0644\u060c \u0646\u0647\u0646\u06af\u200c\u0647\u0627\u06cc \u06a9\u0631\u06cc\u067e\u062a\u0648 \u0635\u062f\u0647\u0627 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 <\/span><a href=\"https:\/\/kebrin.ir\/price\/BTC-USDT\"><span style=\"font-weight: 400;\">\u0628\u06cc\u062a\u200c \u06a9\u0648\u06cc\u0646<\/span><\/a><span style=\"font-weight: 400;\"> (BTC)\u060c <\/span><a href=\"https:\/\/kebrin.ir\/price\/ETH-USDT\"><span style=\"font-weight: 400;\">\u0627\u062a\u0631\u06cc\u0648\u0645<\/span><\/a><span style=\"font-weight: 400;\"> (ETH) \u0648 \u0633\u0627\u06cc\u0631 \u0622\u0644\u062a\u200c\u06a9\u0648\u06cc\u0646\u200c\u0647\u0627 \u0631\u0627 \u062c\u0627\u0628\u0647\u200c\u062c\u0627 \u06a9\u0631\u062f\u0646\u062f\u061b \u0627\u0642\u062f\u0627\u0645\u06cc \u06a9\u0647 \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u200c\u0647\u0627\u06cc \u0627\u0646\u0628\u0627\u0634\u062a \u0648 \u0628\u0631\u062f\u0627\u0634\u062a \u0633\u0648\u062f \u062f\u0631 \u0645\u06cc\u0627\u0646 \u062f\u0627\u0631\u0646\u062f\u06af\u0627\u0646 \u0628\u0632\u0631\u06af \u062f\u0627\u0631\u0627\u06cc\u06cc \u0627\u0633\u062a.\u00a0<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%86%D9%87%D9%86%DA%AF%E2%80%8C%D9%87%D8%A7_%D8%A8%D8%A7_%D8%AA%D8%B1%D8%A7%DA%A9%D9%86%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A8%D8%B2%D8%B1%DA%AF_%D9%BE%D8%B1%D8%AA%D9%81%D9%88%DB%8C_%D8%AE%D9%88%D8%AF_%D8%B1%D8%A7_%D8%A8%D8%A7%D8%B2%D8%AA%D9%88%D8%B2%DB%8C%D8%B9_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D9%86%D8%AF\"><\/span><b>\u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u0628\u0627 \u062a\u0631\u0627\u06a9\u0646\u0634\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u067e\u0631\u062a\u0641\u0648\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0632\u062a\u0648\u0632\u06cc\u0639 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u062f\u0648 \u0631\u0645\u0632\u0627\u0631\u0632 \u0628\u0632\u0631\u06af \u0628\u0627\u0632\u0627\u0631 \u0634\u0627\u0647\u062f \u0641\u0639\u0627\u0644\u06cc\u062a \u0642\u0627\u0628\u0644\u200c\u062a\u0648\u062c\u0647 \u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u0628\u0648\u062f\u0646\u062f\u061b \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u062f\u0631\u0648\u0646\u200c\u0632\u0646\u062c\u06cc\u0631\u0647\u200c\u0627\u06cc \u0646\u06cc\u0632 \u0627\u06cc\u0646 \u0631\u0648\u0646\u062f \u0631\u0627 \u062a\u0627\u06cc\u06cc\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062a\u062d\u0644\u06cc\u0644\u06af\u0631 EmberCN \u06af\u0632\u0627\u0631\u0634 \u062f\u0627\u062f \u06a9\u0647 \u06cc\u06a9 \u0646\u0647\u0646\u06af\u060c \u06f2\u06f0\u066c\u06f0\u06f2\u06f1 \u0648\u0627\u062d\u062f ETH \u0628\u0647 \u0627\u0631\u0632\u0634 \u062a\u0642\u0631\u06cc\u0628\u06cc \u06f7\u06f8.\u06f1\u06f5 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0627\u0632 \u0628\u0627\u06cc\u0646\u0646\u0633 \u062e\u0627\u0631\u062c \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0645\u0639\u0627\u0645\u0644\u0647\u200c\u06af\u0631 \u06cc\u0627 \u0646\u0647\u0627\u062f \u067e\u06cc\u0634\u200c\u062a\u0631 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06f7\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 USDC \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u0648\u062b\u06cc\u0642\u0647\u060c \u062d\u062f\u0648\u062f \u06f2\u06f6\u06f2 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0627\u062a\u0631\u06cc\u0648\u0645 \u0648\u0627\u0645 \u06af\u0631\u0641\u062a\u0647 \u0628\u0648\u062f \u06a9\u0647 \u0627\u062d\u062a\u0645\u0627\u0644\u0627\u064b \u0628\u0631\u0627\u06cc \u0645\u0648\u0642\u0639\u06cc\u062a \u0641\u0631\u0648\u0634 (Short) \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">EmberCN \u0646\u0648\u0634\u062a: \u00ab\u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0648 \u062f\u0648 \u0647\u0641\u062a\u0647 \u067e\u06cc\u0634 \u0631\u0648\u06cc ETH \u067e\u0648\u0632\u06cc\u0634\u0646 \u0641\u0631\u0648\u0634 \u0628\u0627\u0632 \u06a9\u0631\u062f\u060c \u0642\u06cc\u0645\u062a \u062f\u0631 \u0633\u0637\u062d \u06f4\u066c\u06f0\u06f3\u06f2 \u062f\u0644\u0627\u0631 \u0628\u0648\u062f. \u0627\u06a9\u0646\u0648\u0646 \u06a9\u0647 ETH \u062f\u0631 \u0645\u062d\u062f\u0648\u062f\u0647 \u06f3\u066c\u06f8\u06f5\u06f0 \u062f\u0644\u0627\u0631 \u0645\u0639\u0627\u0645\u0644\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u0627\u062d\u062a\u0645\u0627\u0644\u0627\u064b \u062d\u062f\u0648\u062f \u06f1\u06f2 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0633\u0648\u062f \u0628\u0631\u0627\u06cc \u0627\u0648 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a.\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631\u060c \u0646\u0647\u0646\u06af \u062f\u06cc\u06af\u0631\u06cc \u06a9\u0647 \u062f\u0631 \u067e\u0644\u062a\u0641\u0631\u0645 Aave \u062f\u0627\u0631\u0627\u06cc \u0645\u0648\u0642\u0639\u06cc\u062a \u062e\u0631\u06cc\u062f (Long) \u0627\u062a\u0631\u06cc\u0648\u0645 \u0628\u0648\u062f\u060c \u06f2\u066c\u06f5\u06f0\u06f0 ETH \u0628\u0647 \u0627\u0631\u0632\u0634 \u06f9.\u06f6\u06f7 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0631\u0627 \u0641\u0631\u0648\u062e\u062a \u062a\u0627 \u0645\u06cc\u0632\u0627\u0646 \u0627\u0647\u0631\u0645 (Leverage) \u062e\u0648\u062f \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0647\u062f. \u0627\u06cc\u0646 \u0645\u0639\u0627\u0645\u0644\u0647\u200c\u06af\u0631 \u067e\u06cc\u0634\u200c\u062a\u0631 \u06f2\u066c\u06f9\u06f8\u06f9 ETH \u0631\u0627 \u0628\u0627 \u0645\u06cc\u0627\u0646\u06af\u06cc\u0646 \u0642\u06cc\u0645\u062a \u06f4\u066c\u06f1\u06f9\u06f7 \u062f\u0644\u0627\u0631 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0631\u062f\u0647 \u0628\u0648\u062f \u0648 \u0627\u0632 \u0645\u062d\u0644 \u0627\u06cc\u0646 \u0641\u0631\u0648\u0634 \u062d\u062f\u0648\u062f \u06f8\u06f2\u06f0 \u0647\u0632\u0627\u0631 \u062f\u0644\u0627\u0631 \u0632\u06cc\u0627\u0646 \u0645\u062a\u062d\u0645\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u0648 \u0647\u0645\u0686\u0646\u0627\u0646 \u06f1\u06f3\u066c\u06f5\u06f0\u06f4.\u06f5\u06f6 \u0648\u0627\u062d\u062f ETH \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u0648\u062b\u06cc\u0642\u0647 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0631\u062f. \u062f\u0631 \u0647\u0645\u06cc\u0646 \u062d\u0627\u0644\u060c \u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u0645\u0642\u0627\u062f\u06cc\u0631 \u0642\u0627\u0628\u0644\u200c\u062a\u0648\u062c\u0647\u06cc \u0628\u06cc\u062a\u200c\u06a9\u0648\u06cc\u0646 \u0628\u0647 \u0635\u0631\u0627\u0641\u06cc\u200c\u0647\u0627 \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062f\u0646\u062f \u06a9\u0647 \u0646\u0634\u0627\u0646\u0647\u200c\u0627\u06cc \u0627\u0632 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0631\u0627\u06a9\u0646\u0634\u200c\u0647\u0627\u06cc \u06a9\u0644\u0627\u0646 \u062f\u0631 \u0634\u0628\u06a9\u0647 \u0627\u0633\u062a. \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0627\u0632\u06cc\u06af\u0631\u0627\u0646 \u0628\u0627\u0632\u0627\u0631 \u06f3\u06f5\u06f1 BTC \u0631\u0627 \u0628\u0647 \u0628\u0627\u06cc\u0646\u0646\u0633 \u0648\u0627\u0631\u06cc\u0632 \u06a9\u0631\u062f \u0648 \u062d\u062f\u0648\u062f \u06f2\u06f7.\u06f9\u06f7 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0633\u0648\u062f \u06a9\u0633\u0628 \u06a9\u0631\u062f.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc Onchain Lens \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0627\u06cc\u0646 \u0646\u0647\u0646\u06af \u06f3\u06f6\u06f1 BTC \u0628\u0647 \u0627\u0631\u0632\u0634 \u06f1\u06f1.\u06f6\u06f3 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0631\u0627 \u06f3 \u062a\u0627 \u06f4 \u0633\u0627\u0644 \u067e\u06cc\u0634 \u0627\u0632 \u0635\u0631\u0627\u0641\u06cc \u062e\u0627\u0631\u062c \u06a9\u0631\u062f\u0647 \u0648 \u0627\u06a9\u0646\u0648\u0646 \u0647\u0645\u0627\u0646 \u0645\u0642\u062f\u0627\u0631 \u0631\u0627 \u0628\u0627 \u0627\u0631\u0632\u0634 \u06f3\u06f9.\u06f6 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u062f\u0648\u0628\u0627\u0631\u0647 \u0633\u067e\u0631\u062f\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u06cc\u06a9 \u0646\u0647\u0646\u06af \u0642\u062f\u06cc\u0645\u06cc \u0628\u06cc\u062a\u200c\u06a9\u0648\u06cc\u0646 (Bitcoin OG) \u06f5\u06f0\u06f0 BTC \u0628\u0647 \u0627\u0631\u0632\u0634 \u06f5\u06f5.\u06f2\u06f8 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0628\u0647 \u06a9\u0631\u0627\u06a9\u0646 \u0627\u0631\u0633\u0627\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Onchain Lens \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062a\u0627\u06a9\u06cc\u062f \u06a9\u0631\u062f: \u00ab\u0627\u06cc\u0646 \u0646\u0647\u0646\u06af \u0642\u062f\u06cc\u0645\u06cc \u062f\u0631 \u0645\u062c\u0645\u0648\u0639 \u0637\u06cc \u0633\u0647 \u0647\u0641\u062a\u0647 \u06af\u0630\u0634\u062a\u0647 <\/span><b>\u06f7\u066c\u06f0\u06f0\u06f3 \u0628\u06cc\u062a\u200c\u06a9\u0648\u06cc\u0646 \u0628\u0647 \u0627\u0631\u0632\u0634 \u06f7\u06f8\u06f1.\u06f8\u06f1 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631<\/b><span style=\"font-weight: 400;\"> \u0628\u0647 \u0635\u0631\u0627\u0641\u06cc\u200c\u0647\u0627\u06cc \u0645\u062a\u0645\u0631\u06a9\u0632 \u0648\u0627\u0631\u06cc\u0632 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u06a9\u0627\u0631\u0628\u0631 Owen Gunden \u0645\u0642\u062f\u0627\u0631 \u06f1\u06f9\u06f3.\u06f7\u06f7 \u0628\u06cc\u062a\u200c\u06a9\u0648\u06cc\u0646 \u0645\u0639\u0627\u062f\u0644 \u06f2\u06f1.\u06f4\u06f9 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0631\u0627 \u0628\u0647 \u06a9\u0631\u0627\u06a9\u0646 \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0627\u0648 \u0647\u0645\u0686\u0646\u0627\u0646 \u06f8\u066c\u06f9\u06f2\u06f2 BTC \u0628\u0647 \u0627\u0631\u0632\u0634 \u062d\u062f\u0648\u062f \u06f9\u06f9\u06f0.\u06f8\u06f5 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0631\u062f.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D9%88%D8%AC%D9%87_%D9%86%D9%87%D9%86%DA%AF%E2%80%8C%D9%87%D8%A7_%D8%A8%D9%87_%D8%A2%D9%84%D8%AA%E2%80%8C%DA%A9%D9%88%DB%8C%D9%86%E2%80%8C%D9%87%D8%A7\"><\/span><b>\u062a\u0648\u062c\u0647 \u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u0628\u0647 \u0622\u0644\u062a\u200c\u06a9\u0648\u06cc\u0646\u200c\u0647\u0627<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u0641\u0631\u0627\u062a\u0631 \u0627\u0632 BTC \u0648 ETH\u060c \u0633\u0627\u06cc\u0631 \u0622\u0644\u062a\u200c\u06a9\u0648\u06cc\u0646\u200c\u0647\u0627 \u0646\u06cc\u0632 \u0645\u0648\u0631\u062f \u062a\u0648\u062c\u0647 \u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646\u062f.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"> \u0686\u0627\u0646\u06af\u200c\u067e\u0646\u06af \u0698\u0627\u0626\u0648 (CZ)\u060c \u0628\u0646\u06cc\u0627\u0646\u200c\u06af\u0630\u0627\u0631 \u0628\u0627\u06cc\u0646\u0646\u0633\u060c \u062f\u0631 \u062a\u0627\u0631\u06cc\u062e \u06f2 \u0646\u0648\u0627\u0645\u0628\u0631 \u0627\u0632 \u062e\u0631\u06cc\u062f \u06f2 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 <\/span><a href=\"https:\/\/kebrin.ir\/price\/ASTER-USDT\"><span style=\"font-weight: 400;\">\u062a\u0648\u06a9\u0646 ASTER<\/span><\/a><span style=\"font-weight: 400;\"> \u062e\u0628\u0631 \u062f\u0627\u062f. \u0628\u0647\u200c\u0637\u0648\u0631 \u062c\u062f\u0627\u06af\u0627\u0646\u0647\u060c \u06cc\u06a9 \u0646\u0647\u0646\u06af \u06f5.\u06f8 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0648\u0627\u062d\u062f ASTER \u0628\u0647 \u0627\u0631\u0632\u0634 \u06f5.\u06f5\u06f8 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0627\u0632 \u0628\u0627\u06cc\u0646\u0646\u0633 \u0628\u0631\u062f\u0627\u0634\u062a \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">OnChain Lens \u0627\u0641\u0632\u0648\u062f: \u00ab\u062f\u0631 \u0634\u0634 \u0631\u0648\u0632 \u06af\u0630\u0634\u062a\u0647\u060c \u0627\u06cc\u0646 \u0646\u0647\u0646\u06af \u0645\u062c\u0645\u0648\u0639\u0627 \u06f6.\u06f8 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062a\u0648\u06a9\u0646 ASTER \u0628\u0647 \u0627\u0631\u0632\u0634 \u06f6.\u06f6\u06f6 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0627\u0632 \u0628\u0627\u06cc\u0646\u0646\u0633 \u062e\u0627\u0631\u062c \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.\u00bb \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u067e\u0644\u062a\u0641\u0631\u0645 Lookonchain \u06af\u0632\u0627\u0631\u0634 \u062f\u0627\u062f \u06a9\u0647 \u0633\u0647 \u06a9\u06cc\u0641 \u067e\u0648\u0644 \u0645\u062c\u0645\u0648\u0639\u0627 \u06f2.\u06f2\u06f6 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062a\u0648\u06a9\u0646 GHOST \u0631\u0627 \u062f\u0631 \u0622\u062e\u0631 \u0647\u0641\u062a\u0647 \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0631\u062f\u0646\u062f. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"> \u06cc\u06a9\u06cc \u0627\u0632 \u0646\u0647\u0646\u06af\u200c\u0647\u0627\u06cc <\/span><a href=\"https:\/\/kebrin.ir\/price\/SOL-USDT\"><span style=\"font-weight: 400;\">\u0633\u0648\u0644\u0627\u0646\u0627<\/span><\/a><span style=\"font-weight: 400;\"> (SOL) \u06a9\u0647 \u06f1\u06f0 \u0645\u0627\u0647 \u063a\u06cc\u0631\u0641\u0639\u0627\u0644 \u0628\u0648\u062f\u060c \u06f1.\u06f1\u06f2 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062a\u0648\u06a9\u0646 GHOST \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0631\u062f\u0647 \u0648 \u0639\u0644\u0627\u0642\u0647 \u0686\u0634\u0645\u200c\u06af\u06cc\u0631\u06cc \u0628\u0647 \u0627\u06cc\u0646 \u0631\u0645\u0632\u0627\u0631\u0632 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D9%88%D9%82%D8%B9%DB%8C%D8%AA_%D9%86%D9%87%D9%86%DA%AF%E2%80%8C%D9%87%D8%A7_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B2%D8%A7%D8%B1_%D9%85%D8%B4%D8%AA%D9%82%D8%A7%D8%AA\"><\/span><b>\u0645\u0648\u0642\u0639\u06cc\u062a \u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0634\u062a\u0642\u0627\u062a<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0634\u062a\u0642\u0627\u062a\u060c \u0628\u0627\u0632\u06cc\u06af\u0631\u0627\u0646 \u0628\u0632\u0631\u06af \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0632\u062a\u0646\u0638\u06cc\u0645 \u06a9\u0631\u062f\u0646\u062f \u06a9\u0647 \u0646\u0634\u0627\u0646 \u0627\u0632 <\/span><b>\u0627\u062d\u0633\u0627\u0633\u0627\u062a \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0648 \u0627\u062d\u062a\u06cc\u0627\u0637\u200c\u0622\u0645\u06cc\u0632<\/b><span style=\"font-weight: 400;\"> \u062f\u0627\u0631\u062f.\u00a0 \u06cc\u06a9 \u0646\u0647\u0646\u06af \u06a9\u0631\u06cc\u067e\u062a\u0648\u06cc\u06cc \u0628\u0627 <\/span><b>\u0646\u0631\u062e \u0645\u0648\u0641\u0642\u06cc\u062a \u06f1\u06f0\u06f0 \u062f\u0631\u0635\u062f\u06cc<\/b><span style=\"font-weight: 400;\">\u060c \u0645\u06cc\u0632\u0627\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u062e\u0631\u06cc\u062f \u062e\u0648\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0628\u0647 \u06af\u0641\u062a\u0647 Lookonchain: \u00ab\u0645\u0639\u0627\u0645\u0644\u0647\u200c\u06af\u0631 \u0647\u0648\u0634\u0645\u0646\u062f 0xc2a3 \u06a9\u0647 \u0646\u0631\u062e \u0628\u0631\u062f \u06f1\u06f0\u06f0 \u062f\u0631\u0635\u062f\u06cc \u062f\u0627\u0631\u062f\u060c \u0647\u0645\u0686\u0646\u0627\u0646 \u0628\u0647 \u0627\u0641\u0632\u0648\u062f\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u0644\u0627\u0646\u06af \u062f\u0631 BTC\u060c ETH \u0648 SOL \u0627\u062f\u0627\u0645\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f!<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"> \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u0641\u0639\u0644\u06cc \u0627\u0648: \u06f3\u06f9\u066c\u06f0\u06f0\u06f0 ETH (\u0628\u0647 \u0627\u0631\u0632\u0634 \u06f1\u06f5\u06f1 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631)\u060c \u06f1\u066c\u06f0\u06f7\u06f0 BTC (\u06f1\u06f1\u06f8 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631) \u0648 \u06f5\u06f6\u06f9\u066c\u06f0\u06f5\u06f0 SOL (\u06f1\u06f0\u06f5 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631).\u00a0 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0633\u0641\u0627\u0631\u0634 \u0645\u062d\u062f\u0648\u062f (Limit Order) \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f \u06f4\u06f0\u066c\u06f0\u06f0\u06f0 SOL \u062f\u06cc\u06af\u0631 \u0628\u0647 \u0627\u0631\u0632\u0634 \u06f7.\u06f3\u06f6 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u062f\u0631 \u0642\u06cc\u0645\u062a \u06f1\u06f8\u06f4 \u062f\u0644\u0627\u0631 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a.\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631\u060c \u0645\u0639\u0627\u0645\u0644\u0647\u200c\u06af\u0631 0x8d0E \u0645\u0642\u062f\u0627\u0631 \u06f1\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646 USDC \u0631\u0627 \u0628\u0647 \u067e\u0644\u062a\u0641\u0631\u0645 Hyperliquid \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062f\u0647 \u0648 \u0645\u0648\u0642\u0639\u06cc\u062a \u062e\u0631\u06cc\u062f \u0628\u0627 \u0627\u0647\u0631\u0645 \u06f2\u06f0 \u0628\u0631\u0627\u0628\u0631\u06cc \u0631\u0648\u06cc \u06f1\u06f4\u06f0\u066c\u06f3\u06f6\u06f6 SOL \u0628\u0647 \u0627\u0631\u0632\u0634 \u062a\u0642\u0631\u06cc\u0628\u06cc \u06f2\u06f6.\u06f1\u06f4 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0628\u0627\u0632 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u0645\u0642\u0627\u0628\u0644\u060c \u06a9\u0627\u0631\u0628\u0631 0x9e4f \u0634\u0631\u0637 \u0628\u0633\u06cc\u0627\u0631 \u067e\u0631\u0631\u06cc\u0633\u06a9\u06cc \u0628\u0633\u062a\u0647 \u0627\u0633\u062a: \u0627\u0648 \u06cc\u06a9 \u0645\u0648\u0642\u0639\u06cc\u062a \u0641\u0631\u0648\u0634 \u0628\u0627 \u0627\u0647\u0631\u0645 \u06f2\u06f5 \u0628\u0631\u0627\u0628\u0631\u06cc \u0631\u0648\u06cc \u06f7\u066c\u06f3\u06f6\u06f8.\u06f8 ETH (\u0628\u0647 \u0627\u0631\u0632\u0634 \u06f2\u06f8.\u06f2 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631) \u0628\u0627 \u0642\u06cc\u0645\u062a \u0648\u0631\u0648\u062f\u06cc \u06f3\u066c\u06f9\u06f0\u06f0.\u06f8\u06f1 \u062f\u0644\u0627\u0631 \u0628\u0627\u0632 \u06a9\u0631\u062f\u0647 \u0648 \u0642\u06cc\u0645\u062a \u0644\u06cc\u06a9\u0648\u06cc\u06cc\u062f \u0634\u062f\u0646 \u062f\u0631 \u0633\u0637\u062d \u06f3\u066c\u06f9\u06f5\u06f3.\u06f3 \u062f\u0644\u0627\u0631 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lookonchain \u062f\u0631\u0628\u0627\u0631\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u0646\u0648\u0634\u062a: \u00ab\u06cc\u0627 \u0633\u0648\u062f \u0628\u0632\u0631\u06af\u06cc \u06a9\u0633\u0628 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u06cc\u0627 \u0628\u0647 \u0633\u0631\u0639\u062a \u0644\u06cc\u06a9\u0648\u06cc\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u062f.\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u062f\u0631 \u0646\u0647\u0627\u06cc\u062a\u060c \u0645\u0639\u0627\u0645\u0644\u0647\u200c\u06af\u0631\u0627\u0646 \u062f\u0631 \u0645\u0648\u0631\u062f \u062a\u0648\u06a9\u0646 ASTER \u0631\u0648\u06cc\u06a9\u0631\u062f\u06cc \u062f\u0641\u0627\u0639\u06cc\u200c\u062a\u0631 \u062f\u0631 \u067e\u06cc\u0634 \u06af\u0631\u0641\u062a\u0646\u062f. \u067e\u0633 \u0627\u0632 \u0627\u0639\u0644\u0627\u0645 \u062e\u0631\u06cc\u062f \u0634\u062e\u0635\u06cc CZ \u0627\u0632 \u0627\u06cc\u0646 \u062a\u0648\u06a9\u0646\u060c \u062f\u0648 \u0645\u0639\u0627\u0645\u0644\u0647\u200c\u06af\u0631 0xbadb \u0648 0x9eec \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u0641\u0631\u0648\u0634 \u062e\u0648\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0627\u062f\u0646\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lookonchain \u06af\u0632\u0627\u0631\u0634 \u062f\u0627\u062f: \u00ab\u0647\u0631 \u062f\u0648 \u0646\u0647\u0646\u06af \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u062f\u0631 \u0645\u0648\u0642\u0639\u06cc\u062a \u0633\u0648\u062f \u0647\u0633\u062a\u0646\u062f \u2014 0x9eec9 \u0628\u0627 \u06f5.\u06f9 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0633\u0648\u062f \u0648 0xbadb \u0628\u0627 \u06f1.\u06f4 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631.\u00bb \u0627\u06cc\u0646 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u200c\u0647\u0627\u06cc \u0645\u062a\u0646\u0648\u0639 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0646\u0647\u0646\u06af\u200c\u0647\u0627 \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0628\u06cc\u0634\u062a\u0631 \u0622\u0645\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0628\u0631 \u0631\u0648\u06cc \u0631\u0645\u0632\u0627\u0631\u0632\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u0645\u0648\u0642\u0639\u06cc\u062a\u200c\u0647\u0627\u06cc \u062e\u0631\u06cc\u062f \u0627\u0647\u0631\u0645\u06cc \u0628\u0627\u0632 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f\u060c \u0631\u0648\u06cc \u062a\u0648\u06a9\u0646\u200c\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9\u200c\u062a\u0631 \u0628\u0647\u200c\u0635\u0648\u0631\u062a \u0647\u062f\u0641\u0645\u0646\u062f \u0634\u0631\u0637 \u0641\u0631\u0648\u0634 \u0628\u0633\u062a\u0647\u200c\u0627\u0646\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0645\u0646\u0628\u0639: <\/span><a href=\"https:\/\/beincrypto.com\/crypto-whales-btc-eth-aster-sol-hype-ghost\/\" rel=\"nofollow noopener\" target=\"_blank\"><span style=\"font-weight: 400;\">beincrypto<\/span><\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;18749&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 \u0627\u0645\u062a\u06cc\u0627\u0632)&quot;,&quot;size&quot;:&quot;18&quot;,&quot;title&quot;:&quot;\u0646\u0647\u0646\u06af\u200c\u0647\u0627\u06cc \u06a9\u0631\u06cc\u067e\u062a\u0648 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0627\u0641\u062a \u0628\u0627\u0632\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u06a9\u062c\u0627 \u0645\u06cc\u200c\u0628\u0631\u0646\u062f\u061f&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 14.4px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0628\u0627\u0632\u0627\u0631 \u0631\u0645\u0632\u0627\u0631\u0632\u0647\u0627 \u062f\u0631 \u0633\u0627\u0639\u0627\u062a \u0627\u0628\u062a\u062f\u0627\u06cc\u06cc \u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0622\u0633\u06cc\u0627\u06cc\u06cc \u0631\u0648\u0632 \u062f\u0648\u0634\u0646\u0628\u0647\u060c \u0633\u0648\u062f \u0622\u062e\u0631 \u0647\u0641\u062a\u0647 \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f \u0648 \u0628\u0627 \u0648\u062c\u0648\u062f \u06a9\u0627\u0647\u0634 \u062a\u0646\u0634\u200c\u0647\u0627\u06cc \u062a\u062c\u0627\u0631\u06cc \u062c\u0647\u0627\u0646\u06cc\u060c \u0628\u0647 \u06f3.\u06f5\u06f9 \u062a\u0631\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0633\u0642\u0648\u0637 \u06a9\u0631\u062f. \u062f\u0631 \u0647\u0645\u06cc\u0646 \u062d\u0627\u0644\u060c \u0646\u0647\u0646\u06af\u200c\u0647\u0627\u06cc \u06a9\u0631\u06cc\u067e\u062a\u0648 \u0635\u062f\u0647\u0627 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0628\u06cc\u062a\u200c \u06a9\u0648\u06cc\u0646 (BTC)\u060c \u0627\u062a\u0631\u06cc\u0648\u0645 (ETH) \u0648 \u0633\u0627\u06cc\u0631 \u0622\u0644\u062a\u200c\u06a9\u0648\u06cc\u0646\u200c\u0647\u0627 \u0631\u0627 \u062c\u0627\u0628\u0647\u200c\u062c\u0627 \u06a9\u0631\u062f\u0646\u062f\u061b \u0627\u0642\u062f\u0627\u0645\u06cc \u06a9\u0647 \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u200c\u0647\u0627\u06cc &hellip;<\/p>\n","protected":false},"author":30,"featured_media":18750,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,149],"tags":[],"class_list":["post-18749","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","category-149"],"_links":{"self":[{"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/posts\/18749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/comments?post=18749"}],"version-history":[{"count":1,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/posts\/18749\/revisions"}],"predecessor-version":[{"id":18751,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/posts\/18749\/revisions\/18751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/media\/18750"}],"wp:attachment":[{"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/media?parent=18749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/categories?post=18749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/tags?post=18749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}