{"id":18923,"date":"2025-11-27T12:51:00","date_gmt":"2025-11-27T09:21:00","guid":{"rendered":"https:\/\/kebrin.ir\/mag\/?p=18923"},"modified":"2025-11-27T12:51:27","modified_gmt":"2025-11-27T09:21:27","slug":"trump-family-1b-dollar-crypto-loss","status":"publish","type":"post","link":"https:\/\/kebrin.ir\/mag\/trump-family-1b-dollar-crypto-loss","title":{"rendered":"\u0632\u06cc\u0627\u0646 \u06cc\u06a9\u200c \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062a\u0631\u0627\u0645\u067e \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0631\u06cc\u067e\u062a\u0648"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 ez-toc-wrap-left-text counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/kebrin.ir\/mag\/trump-family-1b-dollar-crypto-loss\/#%D8%AE%D8%B1%DB%8C%D8%AF_SPSC_%D8%AA%D9%88%D8%B3%D8%B7_WLFI\" >\u062e\u0631\u06cc\u062f SPSC \u062a\u0648\u0633\u0637 WLFI<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/kebrin.ir\/mag\/trump-family-1b-dollar-crypto-loss\/#%D8%A7%D9%86%D8%AA%D9%82%D8%A7%D8%AF_Coffeezilla_%D9%88_%D8%AC%D8%A7%D9%85%D8%B9%D9%87_%DA%A9%D8%B1%DB%8C%D9%BE%D8%AA%D9%88_%D8%A7%D8%B2_WLFI\" >\u0627\u0646\u062a\u0642\u0627\u062f Coffeezilla \u0648 \u062c\u0627\u0645\u0639\u0647 \u06a9\u0631\u06cc\u067e\u062a\u0648 \u0627\u0632 WLFI<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/kebrin.ir\/mag\/trump-family-1b-dollar-crypto-loss\/#%D8%B2%DB%8C%D8%A7%D9%86_%D8%A8%DB%8C%D8%B4_%D8%A7%D8%B2_%DB%8C%DA%A9_%D9%85%DB%8C%D9%84%DB%8C%D8%A7%D8%B1%D8%AF_%D8%AF%D9%84%D8%A7%D8%B1%DB%8C_%D8%AE%D8%A7%D9%86%D9%88%D8%A7%D8%AF%D9%87_%D8%AA%D8%B1%D8%A7%D9%85%D9%BE\" >\u0632\u06cc\u0627\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u06cc\u06a9 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062a\u0631\u0627\u0645\u067e<\/a><\/li><\/ul><\/nav><\/div>\n<p><span style=\"font-weight: 400;\">\u067e\u0631\u0648\u0698\u0647 \u0631\u0645\u0632\u0627\u0631\u0632\u06cc \u00ab\u0648\u0631\u0644\u062f \u0644\u06cc\u0628\u0631\u062a\u06cc \u0641\u0627\u06cc\u0646\u0646\u0634\u0627\u0644\u00bb (World Liberty Financial \u06cc\u0627 WLFI) \u06a9\u0647 \u0628\u0627 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0631\u0626\u06cc\u0633\u200c\u062c\u0645\u0647\u0648\u0631 \u062f\u0648\u0646\u0627\u0644\u062f \u062a\u0631\u0627\u0645\u067e \u0645\u0631\u062a\u0628\u0637 \u0627\u0633\u062a\u060c \u0631\u0648\u0632 \u0633\u0647\u200c\u0634\u0646\u0628\u0647 \u067e\u0633 \u0627\u0632 \u062a\u0627\u06cc\u06cc\u062f \u0639\u0645\u0648\u0645\u06cc \u06cc\u06a9 \u062a\u0648\u06a9\u0646 \u0634\u0648\u062e\u06cc \u0628\u0627 \u0646\u0627\u0645 \u00abSh<\/span><i><span style=\"font-weight: 400;\">t P<\/span><\/i><span style=\"font-weight: 400;\">ss Skin Can\u00bb (SPSC) \u0628\u0627 \u0627\u0646\u062a\u0642\u0627\u062f \u0645\u0648\u0627\u062c\u0647 \u0634\u062f.\u00a0<\/span><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u062d\u0645\u0627\u06cc\u062a \u062f\u0631\u062d\u0627\u0644\u06cc \u0635\u0648\u0631\u062a \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f \u06a9\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0634\u0627\u062e\u0635 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f\u0631\u0647\u0627\u06cc \u0628\u0644\u0648\u0645\u0628\u0631\u06af\u060c \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062a\u0631\u0627\u0645\u067e \u062f\u0631 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644 \u0628\u06cc\u0634 \u0627\u0632 \u06cc\u06a9 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631 \u0632\u06cc\u0627\u0646 \u062b\u0628\u062a \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a\u061b \u0627\u0632 \u062c\u0645\u0644\u0647 \u0636\u0631\u0631 \u0642\u0627\u0628\u0644\u200c\u062a\u0648\u062c\u0647 \u062f\u0631 \u0628\u06cc\u062a\u200c\u06a9\u0648\u06cc\u0646.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AE%D8%B1%DB%8C%D8%AF_SPSC_%D8%AA%D9%88%D8%B3%D8%B7_WLFI\"><\/span><b>\u062e\u0631\u06cc\u062f SPSC \u062a\u0648\u0633\u0637 WLFI<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">WLFI \u0631\u0648\u0632 \u062f\u0648\u0634\u0646\u0628\u0647 \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f \u06a9\u0647 \u062e\u0631\u06cc\u062f \u0645\u06cc\u0645\u200c\u06a9\u0648\u06cc\u0646 SPSC\u060c \u062a\u0648\u06a9\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0627\u062f\u0627\u06cc \u0627\u062d\u062a\u0631\u0627\u0645 \u0628\u0647 \u0686\u06cc\u0633 \u0647\u06cc\u0631\u0648 (Chase Herro)\u060c \u0647\u0645\u200c\u0628\u0646\u06cc\u0627\u0646\u200c\u06af\u0630\u0627\u0631 WLFI \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647\u060c \u0631\u0627 \u0622\u063a\u0627\u0632 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0647\u06cc\u0631\u0648 \u0628\u0647\u200c\u062e\u0627\u0637\u0631 \u0627\u0638\u0647\u0627\u0631\u0646\u0638\u0631\u06cc \u06a9\u0647 \u0686\u0646\u062f \u0633\u0627\u0644 \u067e\u06cc\u0634 \u0645\u0637\u0631\u062d \u06a9\u0631\u062f\u0647 \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u061b \u0627\u0648 \u06af\u0641\u062a\u0647 \u0628\u0648\u062f \u062d\u062a\u06cc \u06cc\u06a9 \u0642\u0648\u0637\u06cc \u0632\u0628\u0627\u0644\u0647 \u0627\u0646\u0633\u0627\u0646\u06cc \u0647\u0645 \u00ab\u0627\u06af\u0631 \u062f\u0627\u0633\u062a\u0627\u0646\u0634 \u062f\u0631\u0633\u062a \u0628\u0627\u0634\u062f \u06cc\u06a9 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631 \u0641\u0631\u0648\u0634 \u0645\u06cc\u200c\u0631\u0648\u062f\u00bb.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">WLFI \u062f\u0631 \u0634\u0628\u06a9\u0647 \u0627\u06cc\u06a9\u0633 \u0646\u0648\u0634\u062a: \u00ab\u062f\u0631 \u062d\u0627\u0644 \u062e\u0631\u06cc\u062f SPSC \u0647\u0633\u062a\u06cc\u0645\u060c \u0686\u0648\u0646 \u0628\u0627\u0644\u0627\u062e\u0631\u0647 \u0627\u0641\u0631\u0627\u062f \u062e\u0637 \u0645\u0642\u062f\u0645 \u062f\u0631 \u0645\u06cc\u0645\u200c\u0647\u0627\u06cc \u06cc\u06a9\u200c\u062f\u0644\u0627\u0631\u06cc \u0628\u0647 \u0628\u0627\u0648\u0631 \u0631\u0633\u06cc\u062f\u0647\u200c\u0627\u0646\u062f. \u0627\u06af\u0631 \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u06a9\u0648\u06cc\u0646\u06cc \u0628\u0647 \u0627\u0641\u062a\u062e\u0627\u0631 \u0647\u0645\u200c\u0628\u0646\u06cc\u0627\u0646\u200c\u06af\u0630\u0627\u0631 WLFI \u0628\u0633\u0627\u0632\u0646\u062f\u2026 \u0645\u0627 \u0647\u0645 \u0648\u0627\u0631\u062f \u0645\u06cc\u200c\u0634\u0648\u06cc\u0645.\u00bb \u0627\u06cc\u0646 \u067e\u0633\u062a \u0628\u0627\u0639\u062b \u062c\u0647\u0634 \u0633\u0641\u062a\u0647\u200c\u0628\u0627\u0632\u0627\u0646\u0647 \u0633\u0631\u06cc\u0639 \u0634\u062f \u0648 \u0642\u06cc\u0645\u062a SPSC \u062a\u0627 \u06f1\u06f4\u06f3 \u062f\u0631\u0635\u062f \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0641\u062a.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D8%AA%D9%82%D8%A7%D8%AF_Coffeezilla_%D9%88_%D8%AC%D8%A7%D9%85%D8%B9%D9%87_%DA%A9%D8%B1%DB%8C%D9%BE%D8%AA%D9%88_%D8%A7%D8%B2_WLFI\"><\/span><b>\u0627\u0646\u062a\u0642\u0627\u062f Coffeezilla \u0648 \u062c\u0627\u0645\u0639\u0647 \u06a9\u0631\u06cc\u067e\u062a\u0648 \u0627\u0632 WLFI<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u062a\u0635\u0645\u06cc\u0645 \u0628\u0644\u0627\u0641\u0627\u0635\u0644\u0647 \u0628\u0627 \u0648\u0627\u06a9\u0646\u0634 \u0645\u0646\u0641\u06cc \u062a\u062d\u0644\u06cc\u0644\u06af\u0631\u0627\u0646 \u06a9\u0631\u06cc\u067e\u062a\u0648 \u0648 \u0645\u0639\u0627\u0645\u0644\u0647\u200c\u06af\u0631\u0627\u0646 \u0622\u0646\u0644\u0627\u06cc\u0646 \u0645\u0648\u0627\u062c\u0647 \u0634\u062f. \u06a9\u0648\u064f\u0641\u06cc\u0632\u0644\u0627\u060c \u06cc\u0648\u062a\u06cc\u0648\u0628\u0631 \u0648 \u067e\u0698\u0648\u0647\u0634\u06af\u0631 \u06a9\u0644\u0627\u0647\u0628\u0631\u062f\u0627\u0631\u06cc\u060c WLFI \u0631\u0627 \u0628\u0647\u200c\u062e\u0627\u0637\u0631 \u062a\u0631\u0648\u06cc\u062c \u06cc\u06a9 \u06a9\u0648\u06cc\u0646 \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u06cc\u06a9 \u0634\u0648\u062e\u06cc \u062f\u0631\u0628\u0627\u0631\u0647 \u2018sh*t p*ss skin can\u2019 \u0645\u0648\u0631\u062f \u0627\u0646\u062a\u0642\u0627\u062f \u0642\u0631\u0627\u0631 \u062f\u0627\u062f. \u0627\u0648 \u0628\u0647 \u062a\u0646\u0627\u0642\u0636 \u0645\u06cc\u0627\u0646 \u0647\u062f\u0641 \u0627\u062f\u0639\u0627\u06cc\u06cc WLFI \u0645\u0628\u0646\u06cc \u0628\u0631 \u00ab\u0633\u0627\u062e\u062a\u0646 \u0622\u06cc\u0646\u062f\u0647 \u0645\u0627\u0644\u06cc\u00bb \u0648 \u062a\u0631\u0648\u06cc\u062c \u06cc\u06a9 \u062a\u0648\u06a9\u0646 \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u0645\u06cc\u0645 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0633\u0627\u06cc\u0631 \u0645\u0639\u0627\u0645\u0644\u0647\u200c\u06af\u0631\u0627\u0646 \u0646\u06cc\u0632 \u062f\u0631 \u0634\u0628\u06a9\u0647 X \u0646\u0642\u062f\u0647\u0627\u06cc \u0645\u0634\u0627\u0628\u0647\u06cc \u0631\u0627 \u0645\u0637\u0631\u062d \u06a9\u0631\u062f\u0646\u062f \u0648 \u06af\u0641\u062a\u0646\u062f \u062a\u0627\u06cc\u06cc\u062f \u06cc\u06a9 \u062a\u0648\u06a9\u0646 \u0645\u0628\u062a\u0646\u06cc\u200c\u0628\u0631 \u0634\u0648\u06a9 \u0648 \u0634\u0648\u062e\u06cc\u060c \u0627\u0639\u062a\u0628\u0627\u0631 \u067e\u0631\u0648\u0698\u0647 \u0631\u0627 \u0645\u062e\u062f\u0648\u0634 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u06cc\u06a9 \u06a9\u0627\u0631\u0628\u0631 \u0646\u0648\u0634\u062a: \u00ab\u062d\u062a\u06cc \u0632\u062d\u0645\u062a \u0646\u06a9\u0634\u06cc\u062f\u0646\u062f \u067e\u0633\u062a \u0631\u0627 \u062f\u0631\u0633\u062a \u0628\u0646\u0648\u06cc\u0633\u0646\u062f\u060c \u0641\u0642\u0637 \u0627\u0632 chatgpt \u062e\u0648\u0627\u0633\u062a\u0646\u062f \u062a\u0648\u0644\u06cc\u062f \u06a9\u0646\u062f.\u00bb \u06a9\u0627\u0631\u0628\u0631 \u062f\u06cc\u06af\u0631\u06cc \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f: \u00ab\u0634\u06cc\u062a\u200c\u06a9\u0648\u06cc\u0646\u200c\u0647\u0627 \u0622\u0646\u200c\u0642\u062f\u0631 \u0645\u0635\u0646\u0648\u0639\u06cc \u0648 \u0633\u0627\u062e\u062a\u06af\u06cc \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u0648\u0627\u0642\u0639\u0627 \u0622\u062f\u0645 \u0631\u0627 \u0628\u0647 \u062a\u0647\u0648\u0639 \u0645\u06cc\u200c\u0627\u0646\u062f\u0627\u0632\u0646\u062f.\u00bb<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B2%DB%8C%D8%A7%D9%86_%D8%A8%DB%8C%D8%B4_%D8%A7%D8%B2_%DB%8C%DA%A9_%D9%85%DB%8C%D9%84%DB%8C%D8%A7%D8%B1%D8%AF_%D8%AF%D9%84%D8%A7%D8%B1%DB%8C_%D8%AE%D8%A7%D9%86%D9%88%D8%A7%D8%AF%D9%87_%D8%AA%D8%B1%D8%A7%D9%85%D9%BE\"><\/span><b>\u0632\u06cc\u0627\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u06cc\u06a9 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062a\u0631\u0627\u0645\u067e<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u062c\u0646\u062c\u0627\u0644 \u062f\u0631 \u062d\u0627\u0644\u06cc \u0634\u06a9\u0644 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f \u06a9\u0647 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062a\u0631\u0627\u0645\u067e \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0633\u0642\u0648\u0637 \u0634\u062f\u06cc\u062f \u062f\u0631 \u0633\u0628\u062f \u06af\u0633\u062a\u0631\u062f\u0647 \u0631\u0645\u0632\u0627\u0631\u0632\u06cc \u062e\u0648\u062f \u0628\u0627 \u0641\u0634\u0627\u0631 \u0645\u0627\u0644\u06cc \u0631\u0648\u200c\u0628\u0647\u200c\u0627\u0641\u0632\u0648\u0646 \u0645\u0648\u0627\u062c\u0647 \u0627\u0633\u062a. \u0628\u0647\u200c\u06af\u0641\u062a\u0647 \u0628\u0644\u0648\u0645\u0628\u0631\u06af\u060c \u0627\u0631\u0632\u0634 \u062e\u0627\u0644\u0635 \u062f\u0627\u0631\u0627\u06cc\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0637\u06cc \u0645\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u062e\u06cc\u0631 \u0628\u06cc\u0634 \u0627\u0632 \u06cc\u06a9 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631 \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0641\u062a\u0647 \u06a9\u0647 \u0639\u0645\u062f\u062a\u0627 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0632\u06cc\u0627\u0646\u200c\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646 \u062f\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9 \u06a9\u0631\u06cc\u067e\u062a\u0648 \u0627\u0633\u062a. \u062a\u062d\u0644\u06cc\u0644 \u0628\u0644\u0648\u0645\u0628\u0631\u06af \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0627\u0631\u0632\u0634 \u062f\u0627\u0631\u0627\u06cc\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0627\u0632 \u062d\u062f\u0648\u062f \u06f7.\u06f7 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631 \u062f\u0631 \u0627\u0648\u0627\u06cc\u0644 \u0633\u067e\u062a\u0627\u0645\u0628\u0631 \u0628\u0647 \u062d\u062f\u0648\u062f \u06f6.\u06f7 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631 \u0627\u0645\u0631\u0648\u0632 \u0631\u0633\u06cc\u062f\u0647 \u0627\u0633\u062a. \u0634\u0631\u06a9\u062a Trump Media &amp; Technology Group \u06a9\u0647 \u067e\u06cc\u0634\u200c\u062a\u0631 \u0628\u0631\u0646\u0627\u0645\u0647 \u062e\u0648\u062f \u0628\u0631\u0627\u06cc \u0627\u06cc\u062c\u0627\u062f \u06cc\u06a9 \u062e\u0632\u0627\u0646\u0647 \u0631\u0645\u0632\u0627\u0631\u0632\u06cc \u0631\u0627 \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f\u0647 \u0628\u0648\u062f\u060c \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0632\u06cc\u0627\u0646\u200c\u0647\u0627 \u0631\u0627 \u0645\u062a\u062d\u0645\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0628\u0647\u200c\u06af\u0641\u062a\u0647 \u0628\u0644\u0648\u0645\u0628\u0631\u06af\u060c \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0627\u0641\u062a \u0642\u0627\u0628\u0644\u200c\u062a\u0648\u062c\u0647 \u062f\u0631 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0628\u06cc\u062a\u200c\u06a9\u0648\u06cc\u0646\u060c \u0633\u0647\u0645 \u0631\u0626\u06cc\u0633\u200c\u062c\u0645\u0647\u0648\u0631 \u062a\u0631\u0627\u0645\u067e \u062f\u0631 \u0634\u0631\u06a9\u062a \u0627\u0632 \u0633\u067e\u062a\u0627\u0645\u0628\u0631 \u062a\u0627\u06a9\u0646\u0648\u0646 \u062d\u062f\u0648\u062f \u06f8\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0633\u0642\u0648\u0637 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0628\u0644\u0648\u0645\u0628\u0631\u06af \u06af\u0632\u0627\u0631\u0634 \u062f\u0627\u062f: \u00ab\u0645\u0648\u062c\u0648\u062f\u06cc \u062a\u0642\u0631\u06cc\u0628\u06cc \u06f1\u06f1,\u06f5\u06f0\u06f0 \u0628\u06cc\u062a\u200c\u06a9\u0648\u06cc\u0646\u06cc \u0634\u0631\u06a9\u062a \u06a9\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646\u06cc \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u0634\u062f \u06a9\u0647 \u0642\u06cc\u0645\u062a \u0628\u06cc\u062a\u200c\u06a9\u0648\u06cc\u0646 \u062d\u062f\u0648\u062f \u06f1\u06f1\u06f5 \u0647\u0632\u0627\u0631 \u062f\u0644\u0627\u0631 \u0628\u0648\u062f\u060c \u0627\u06a9\u0646\u0648\u0646 \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u0634\u0631\u06a9\u062a \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u06f2\u06f5 \u062f\u0631\u0635\u062f \u0636\u0631\u0631 \u0631\u0648\u06cc \u0627\u06cc\u0646 \u0645\u0648\u0642\u0639\u06cc\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0633\u062e\u0646\u06af\u0648\u06cc World Liberty Financial \u0628\u0647 \u0628\u0644\u0648\u0645\u0628\u0631\u06af \u06af\u0641\u062a \u0634\u0631\u06a9\u062a \u0647\u0645\u0686\u0646\u0627\u0646 \u0628\u0647 \u0645\u0627\u0645\u0648\u0631\u06cc\u062a \u0628\u0644\u0646\u062f\u0645\u062f\u062a \u062e\u0648\u062f \u067e\u0627\u06cc\u0628\u0646\u062f \u0627\u0633\u062a. \u0627\u0648 \u06af\u0641\u062a: \u00ab\u06a9\u0631\u06cc\u067e\u062a\u0648 \u0645\u0627\u0646\u062f\u06af\u0627\u0631 \u0627\u0633\u062a. \u0648\u0631\u0644\u062f \u0644\u06cc\u0628\u0631\u062a\u06cc \u0641\u0627\u06cc\u0646\u0646\u0634\u0627\u0644 \u0628\u0627\u0648\u0631 \u0628\u0644\u0646\u062f\u0645\u062f\u062a \u0628\u0647 \u0641\u0646\u0627\u0648\u0631\u06cc\u200c\u0647\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u067e\u0634\u062a \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u0646\u062f \u0648 \u0628\u0647\u200c\u0633\u0631\u0639\u062a \u062f\u0631 \u062d\u0627\u0644 \u0628\u0644\u0648\u063a\u200c\u0627\u0646\u062f\u061b \u0645\u0627 \u0645\u0639\u062a\u0642\u062f\u06cc\u0645 \u0627\u06cc\u0646 \u0641\u0646\u0627\u0648\u0631\u06cc\u200c\u0647\u0627 \u062e\u062f\u0645\u0627\u062a \u0645\u0627\u0644\u06cc \u0631\u0627 \u0628\u0647\u200c\u0637\u0648\u0631 \u0628\u0646\u06cc\u0627\u062f\u06cc \u0645\u062a\u062d\u0648\u0644 \u062e\u0648\u0627\u0647\u0646\u062f \u06a9\u0631\u062f.\u00bb<\/span><\/p>\n<p>\u0645\u0646\u0628\u0639: <a href=\"https:\/\/www.ccn.com\/news\/crypto\/how-much-trump-lost-bitcoin-wlfi-memecoin-backlash\/\" rel=\"nofollow noopener\" target=\"_blank\">ccn.com<\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;18923&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 \u0627\u0645\u062a\u06cc\u0627\u0632)&quot;,&quot;size&quot;:&quot;18&quot;,&quot;title&quot;:&quot;\u0632\u06cc\u0627\u0646 \u06cc\u06a9\u200c \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062a\u0631\u0627\u0645\u067e \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0631\u06cc\u067e\u062a\u0648&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 18px; height: 18px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 14.4px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u067e\u0631\u0648\u0698\u0647 \u0631\u0645\u0632\u0627\u0631\u0632\u06cc \u00ab\u0648\u0631\u0644\u062f \u0644\u06cc\u0628\u0631\u062a\u06cc \u0641\u0627\u06cc\u0646\u0646\u0634\u0627\u0644\u00bb (World Liberty Financial \u06cc\u0627 WLFI) \u06a9\u0647 \u0628\u0627 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0631\u0626\u06cc\u0633\u200c\u062c\u0645\u0647\u0648\u0631 \u062f\u0648\u0646\u0627\u0644\u062f \u062a\u0631\u0627\u0645\u067e \u0645\u0631\u062a\u0628\u0637 \u0627\u0633\u062a\u060c \u0631\u0648\u0632 \u0633\u0647\u200c\u0634\u0646\u0628\u0647 \u067e\u0633 \u0627\u0632 \u062a\u0627\u06cc\u06cc\u062f \u0639\u0645\u0648\u0645\u06cc \u06cc\u06a9 \u062a\u0648\u06a9\u0646 \u0634\u0648\u062e\u06cc \u0628\u0627 \u0646\u0627\u0645 \u00abSht Pss Skin Can\u00bb (SPSC) \u0628\u0627 \u0627\u0646\u062a\u0642\u0627\u062f \u0645\u0648\u0627\u062c\u0647 \u0634\u062f.\u00a0\u0627\u06cc\u0646 \u062d\u0645\u0627\u06cc\u062a \u062f\u0631\u062d\u0627\u0644\u06cc \u0635\u0648\u0631\u062a \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f \u06a9\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0634\u0627\u062e\u0635 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f\u0631\u0647\u0627\u06cc \u0628\u0644\u0648\u0645\u0628\u0631\u06af\u060c \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u062a\u0631\u0627\u0645\u067e \u062f\u0631 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644 \u0628\u06cc\u0634 &hellip;<\/p>\n","protected":false},"author":25,"featured_media":18924,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,18],"tags":[],"class_list":["post-18923","post","type-post","status-publish","format-standard","has-post-thumbnail","category-altcoins-news","category-news"],"_links":{"self":[{"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/posts\/18923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/comments?post=18923"}],"version-history":[{"count":1,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/posts\/18923\/revisions"}],"predecessor-version":[{"id":18925,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/posts\/18923\/revisions\/18925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/media\/18924"}],"wp:attachment":[{"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/media?parent=18923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/categories?post=18923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kebrin.ir\/mag\/wp-json\/wp\/v2\/tags?post=18923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}